{"id":456,"date":"2022-07-26T00:23:25","date_gmt":"2022-07-26T00:23:25","guid":{"rendered":"https:\/\/www.cdafootankle.com\/home\/?page_id=456"},"modified":"2023-05-08T21:37:08","modified_gmt":"2023-05-08T21:37:08","slug":"metatarsalgia-deformed-metatarsals","status":"publish","type":"page","link":"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/","title":{"rendered":"Metatarsalgia \/ Deformed Metatarsals"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200&#8243; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<style type=\"text\/css\">#nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { min-height: 200px; } #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: calc( 600 * 100vw \/ 1600 ); } <\/style><div  data-transition=\"slide\" data-overall_style=\"classic\" data-flexible-height=\"true\" data-animate-in-effect=\"slide-down\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"7000\" data-parallax=\"false\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"true\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"false\" data-height=\"600\" data-min-height=\"200\" data-arrows=\"true\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2023\/05\/Copia-de-Copia-de-Copia-de-case112-Video-300-\u00d7-250-px-Video-de-transmision-en-vivo-de-YouTube-1920-\u00d7-600-px-6.jpg);\"> &nbsp; <\/div><\/div><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"auto\" data-tablet-content-width=\"auto\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"left\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2024\/02\/Copia-de-Copia-de-Copia-de-case112-Video-300-\u00d7-250-px-Video-de-transmision-en-vivo-de-YouTube-1920-\u00d7-600-px-15.jpg);\"> &nbsp; <\/div><\/div><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><a href=\"#\" aria-label=\"Previous\" class=\"slider-prev\"><i class=\"icon-salient-left-arrow\"><\/i> <div class=\"slide-count\"> <span class=\"slide-current\">1<\/span> <i class=\"icon-salient-right-line\"><\/i> <span class=\"slide-total\"><\/span> <\/div> <\/a>\n\t\t\t\t\t\t<a href=\"#\" aria-label=\"Next\" class=\"slider-next\"><i class=\"icon-salient-right-arrow\"><\/i> <div class=\"slide-count\"> <span class=\"slide-current\">1<\/span> <i class=\"icon-salient-right-line\"><\/i> <span class=\"slide-total\"><\/span> <\/div> <\/a><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \n\t\t\t\t\t\n\t\t\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-25%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_video link=&#8221;https:\/\/www.youtube.com\/watch?v=DRVI79zP-yU&amp;t=4s&#8221; css=&#8221;.vc_custom_1680618819148{padding-top: 40px !important;}&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-5%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;55&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243; img_link=&#8221;https:\/\/www.cdafootankle.com\/home\/services\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;56&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;800&#8243; img_link=&#8221;https:\/\/www.cdafootankle.com\/home\/mis\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;57&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;1000&#8243; img_link=&#8221;https:\/\/www.cdafootankle.com\/home\/patients-forms\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;58&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;1200&#8243; img_link=&#8221;https:\/\/www.cdafootankle.com\/home\/appointments\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;820&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;1200&#8243; img_link=&#8221;https:\/\/www.cdafootankle.com\/home\/contact\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;8%&#8221; right_padding_desktop=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;2&#8243; divider_color=&#8221;accent-color&#8221; animate=&#8221;yes&#8221; custom_height=&#8221;60&#8243; delay=&#8221;600&#8243;][vc_column_text css=&#8221;.vc_custom_1681724788807{padding-top: 30px !important;}&#8221;]\n<p style=\"text-align: justify;\">Metatarsalgia is a general term used to refer to a painful foot condition in the metatarsal region of the foot (the area between the arch and toes, or ball of the foot).\u00a0 The ball of the foot is a weight bearing area where the metatarsals bear the greatest amount of weight and pressure. If one or more of these metatarsals is out of alignment, then excessive pressure is generated in the area causing pain, inflammation and sometimes producing a callus.\u00a0 Many people say the painful feeling is \u201clike walking on rocks\u201d<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;458&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;8%&#8221; right_padding_desktop=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1092&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1093&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;50&#8243; bottom_margin=&#8221;20&#8243; column_element_direction_desktop=&#8221;horizontal&#8221; column_element_alignment=&#8221;center&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;horizontal&#8221; column_element_alignment=&#8221;center&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h2 style=\"text-align: center;\">STEP BY STEP METATARSALGIA SURGERY<\/h2>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;horizontal&#8221; column_element_alignment=&#8221;center&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_gallery type=&#8221;flexslider_style&#8221; images=&#8221;1095,1096,1097,1098,1099,1100,1101,1102,1103,1104&#8243; onclick=&#8221;link_no&#8221; img_size=&#8221;800&#215;600&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#284c66&#8243; bg_image=&#8221;86&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;100&#8243; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;100&#8243; bottom_margin=&#8221;100&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;100&#8243; bottom_margin=&#8221;100&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Conservative Treatment<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">Conservative treatments for metatarsalgia are often limited\u00a0because they cannot correct any bone deformities that contribute to the symptoms. If conservative treatment fails or the pain progresses to the point where conservative treatment is no longer a viable option, surgical intervention may be needed to correct the deformity.<\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;flexslider_style&#8221; images=&#8221;945,1134&#8243; onclick=&#8221;link_image&#8221; img_size=&#8221;600&#215;600&#8243;][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;10&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">Dr. Nunez does a minimally invasive (<\/span><b>MIS<\/b><span style=\"font-weight: 400;\">) ambulatory surgical technique to correct metatarsalgia. It involves making <\/span><b>\u201cextremely small incision\u201d<\/b><span style=\"font-weight: 400;\"> on top of the foot to correct the affected metatarsal.\u00a0 There is no need for a long open incision thus causing minimal injury to the adjacent tissues <\/span><span style=\"font-weight: 400;\">which results in reduced swelling, pain, and recovery time.<\/span><span style=\"font-weight: 400;\">\u00a0\u00a0<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">MIS surgeons are able to rely on a compression dressing for stabilization immediately after surgery, eliminating the need for internal fixation (pins, screws plates, etc.)<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400;\">\u00a0<\/span>The small surgical incisions enable the surgeon to use fine specially designed instruments to obtain the <b>best cosmetic result<\/b>.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#7f7f7f&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;20&#8243; bottom_margin=&#8221;20&#8243; left_margin=&#8221;20%&#8221; right_margin=&#8221;20%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"font-weight: 400; color: #ffffff;\">Surgery is performed under Fluoroscopic imaging and using just local anesthetic instead of general anesthesia, makes foot surgery possible for some patients who were previously considered to be too at risk for traditional surgery due to age or medical history.\u00a0<\/span><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><span style=\"color: #ffffff;\"><strong>\u00a0<\/strong><span style=\"font-weight: 400;\">There is less trauma to the tissue and surgical times are lessened with this technique, reducing pain and recovery time. Less suturing is necessary and often times no sutures are used. Postoperative patients <\/span><b>ambulate immediately<\/b><span style=\"font-weight: 400;\"> and are placed temporally in a surgical shoe or boot to aid ambulation.<\/span><\/span><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;119&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#284c66&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;150&#8243; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-50&#8243; bottom_margin=&#8221;50&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;700&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]Please call us at (208) 666-0605 or fill out the form below<br \/>\nto submit your information[\/vc_column_text][vc_column_text]<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-35\"><form id=\"wpforms-form-35\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"35\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/home\/wp-json\/wp\/v2\/pages\/456\" data-token=\"e998722b282222f3824ce1769c46bcc4\" data-token-time=\"1783802632\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-35-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-35-field_1\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-35-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-35-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-35-field_2\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-35-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-35-field_9-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-35-field_9\">Phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-35-field_9\" class=\"wpforms-field-medium wpforms-field-required wpforms-masked-input\" data-inputmask=\"&#039;mask&#039;: &#039;(999) 999-9999&#039;\" data-rule-us-phone-field=\"true\" data-inputmask-inputmode=\"tel\" name=\"wpforms[fields][9]\" aria-label=\"Phone\" required><\/div><div id=\"wpforms-35-field_10-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"10\"><label class=\"wpforms-field-label\">Date \/ Time <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-date-type-datepicker\"><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-35-field_10\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][10][date]\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><label for=\"wpforms-35-field_10\" class=\"wpforms-field-sublabel after\">Date<\/label><\/div><div class=\"wpforms-field-row-block\"><input type=\"text\" id=\"wpforms-35-field_10-time\" class=\"wpforms-field-date-time-time wpforms-timepicker wpforms-field-required\" data-time-format=\"g:i A\" data-step=\"30\" data-rule-time12h=\"true\" name=\"wpforms[fields][10][time]\" required><label for=\"wpforms-35-field_10-time\" class=\"wpforms-field-sublabel after\">Time<\/label><\/div><\/div><\/div><div id=\"wpforms-35-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-35-field_7\">Nature of this appointment:<\/label><textarea id=\"wpforms-35-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"35\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages\/456\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-35\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cdafootankle.com\/home\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;80&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;fade-in&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;700&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200&#8243; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-456","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Metatarsalgia \/ Deformed Metatarsals - CDA Foot and Ankle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Metatarsalgia \/ Deformed Metatarsals - CDA Foot and Ankle\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200&#8243; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/\" \/>\n<meta property=\"og:site_name\" content=\"CDA Foot and Ankle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cdafootandankle\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-08T21:37:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/\",\"url\":\"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/\",\"name\":\"Metatarsalgia \/ Deformed Metatarsals - CDA Foot and Ankle\",\"isPartOf\":{\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#website\"},\"datePublished\":\"2022-07-26T00:23:25+00:00\",\"dateModified\":\"2023-05-08T21:37:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cdafootankle.com\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Metatarsalgia \/ Deformed Metatarsals\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#website\",\"url\":\"https:\/\/www.cdafootankle.com\/home\/\",\"name\":\"CDA Foot and Ankle\",\"description\":\"Minimally Invasive Foot Surgery\",\"publisher\":{\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#organization\"},\"alternateName\":\"Minimally Invasive Foot Surgery\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cdafootankle.com\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#organization\",\"name\":\"CDA Foot and Ankle\",\"alternateName\":\"Minimally Invasive Foot Surgery\",\"url\":\"https:\/\/www.cdafootankle.com\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2023\/04\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2023\/04\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"CDA Foot and Ankle\"},\"image\":{\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cdafootandankle\/\",\"https:\/\/www.instagram.com\/cdafootankle\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Metatarsalgia \/ Deformed Metatarsals - CDA Foot and Ankle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/","og_locale":"en_US","og_type":"article","og_title":"Metatarsalgia \/ Deformed Metatarsals - CDA Foot and Ankle","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200&#8243; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221;...","og_url":"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/","og_site_name":"CDA Foot and Ankle","article_publisher":"https:\/\/www.facebook.com\/cdafootandankle\/","article_modified_time":"2023-05-08T21:37:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/","url":"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/","name":"Metatarsalgia \/ Deformed Metatarsals - CDA Foot and Ankle","isPartOf":{"@id":"https:\/\/www.cdafootankle.com\/home\/#website"},"datePublished":"2022-07-26T00:23:25+00:00","dateModified":"2023-05-08T21:37:08+00:00","breadcrumb":{"@id":"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cdafootankle.com\/home\/metatarsalgia-deformed-metatarsals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cdafootankle.com\/home\/"},{"@type":"ListItem","position":2,"name":"Metatarsalgia \/ Deformed Metatarsals"}]},{"@type":"WebSite","@id":"https:\/\/www.cdafootankle.com\/home\/#website","url":"https:\/\/www.cdafootankle.com\/home\/","name":"CDA Foot and Ankle","description":"Minimally Invasive Foot Surgery","publisher":{"@id":"https:\/\/www.cdafootankle.com\/home\/#organization"},"alternateName":"Minimally Invasive Foot Surgery","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cdafootankle.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cdafootankle.com\/home\/#organization","name":"CDA Foot and Ankle","alternateName":"Minimally Invasive Foot Surgery","url":"https:\/\/www.cdafootankle.com\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cdafootankle.com\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2023\/04\/cropped-favicon.png","contentUrl":"https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2023\/04\/cropped-favicon.png","width":512,"height":512,"caption":"CDA Foot and Ankle"},"image":{"@id":"https:\/\/www.cdafootankle.com\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cdafootandankle\/","https:\/\/www.instagram.com\/cdafootankle\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages\/456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/comments?post=456"}],"version-history":[{"count":19,"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages\/456\/revisions"}],"predecessor-version":[{"id":1135,"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages\/456\/revisions\/1135"}],"wp:attachment":[{"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/media?parent=456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}