{"id":283,"date":"2022-03-29T15:55:21","date_gmt":"2022-03-29T15:55:21","guid":{"rendered":"https:\/\/www.cdafootankle.com\/home\/?page_id=283"},"modified":"2023-05-08T14:37:43","modified_gmt":"2023-05-08T14:37:43","slug":"meet-our-team","status":"publish","type":"page","link":"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/","title":{"rendered":"Meet Our Team"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;119&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;50&#8243; bottom_margin=&#8221;50&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<p style=\"text-align: justify;\"><span style=\"color: #ffffff;\">The Coeur d\u2019Alene Foot and Ankle Clinic and Surgery Center has always been committed to hiring dedicated and highly qualified staff members. Most members on our staff have been with us for several years. All team members are devoted to treating every patient with kindness and respect. The needs of our patients always come first, and this is evident in the attitude exhibited by every employee of the Coeur d\u2019Alene Foot and Ankle Clinic and Surgery Center.<\/span><\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; right_padding_desktop=&#8221;1%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;flip-in-vertical&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;600&#8243;][image_with_animation image_url=&#8221;133&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243;][\/vc_column][vc_column column_padding=&#8221;padding-8-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;82&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;accent-color&#8221; animate=&#8221;yes&#8221; custom_height=&#8221;50&#8243; delay=&#8221;700&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"text-align: justify;\">Dr. Orlando N\u00fa\u00f1ez graduated from Rosalind Franklin University of Medical and Science College of Podiatric Medicine in Chicago, Illinois and completed a three-year Podiatric Surgery and Medicine Residency post-graduation at Kendall Regional Medical Center in Miami, Florida. Dr. N\u00fa\u00f1ez is licensed to practice as a Podiatric Surgeon in the states of Idaho and Florida.<\/p>\n[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;More Info&#8221; margin_top=&#8221;20&#8243; url=&#8221;https:\/\/www.cdafootankle.com\/home\/dr-orlando-nunez\/&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#eaeaea&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200&#8243; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;50&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2><span style=\"color: #00a2da;\"><strong>Stephen A. Isham,\u00a0DPM, MD,\u00a0DrHC<\/strong><\/span><\/h2>\n[\/vc_column_text][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;accent-color&#8221; animate=&#8221;yes&#8221; custom_height=&#8221;40&#8243; delay=&#8221;600&#8243;][vc_column_text]\n<p style=\"text-align: justify;\">now retired from his US podiatry domestic practice, originally established the Coeur d\u2019Alene Foot &amp; Ankle Clinic \/ Surgery Center after working since 1976 at the Spokane Foot &amp; Ankle Clinic \/ Surgery Center. Dr. Isham has devoted his career not only to practicing the minimal invasive techniques, but also as Professor of Surgery to teach these procedures at home and abroad. His influence is prominent in many Central American, South American, European and Asian countries. He has pioneered and published articles on many of the minimally invasive surgical procedures currently in use, and several of these techniques bear his name. He has received numerous honors worldwide for his work in this field. Dr. Isham currently continues his work in Minimally Invasive Surgery abroad where he practices at a teaching hospital (San Francisco Hospital) in Mexico City, Mexico and also lectures and teaches around the world at various conferences on Minimally Invasive Surgical Techniques.<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;100&#8243; bottom_margin=&#8221;100&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_cascading_images image_1_url=&#8221;151&#8243; image_1_offset_x_sign=&#8221;+&#8221; image_1_offset_x=&#8221;45%&#8221; image_1_offset_y_sign=&#8221;+&#8221; image_1_offset_y=&#8221;35%&#8221; image_1_rotate_sign=&#8221;+&#8221; image_1_rotate=&#8221;none&#8221; image_1_scale=&#8221;1&#8243; image_1_animation=&#8221;Fade In From Left&#8221; image_1_padding=&#8221;auto&#8221; image_1_box_shadow=&#8221;none&#8221; image_1_max_width_desktop=&#8221;100%&#8221; image_1_max_width_mobile=&#8221;100%&#8221; image_1_image_width_mobile=&#8221;default&#8221; image_2_url=&#8221;287&#8243; image_2_offset_x_sign=&#8221;+&#8221; image_2_offset_x=&#8221;0%&#8221; image_2_offset_y_sign=&#8221;+&#8221; image_2_offset_y=&#8221;0%&#8221; image_2_rotate_sign=&#8221;+&#8221; image_2_rotate=&#8221;none&#8221; image_2_scale=&#8221;1&#8243; image_2_animation=&#8221;Fade In From Bottom&#8221; image_2_padding=&#8221;auto&#8221; image_2_box_shadow=&#8221;none&#8221; image_2_max_width_desktop=&#8221;100%&#8221; image_2_max_width_mobile=&#8221;100%&#8221; image_2_image_width_mobile=&#8221;default&#8221; image_3_offset_x_sign=&#8221;+&#8221; image_3_offset_x=&#8221;0%&#8221; image_3_offset_y_sign=&#8221;+&#8221; image_3_offset_y=&#8221;0%&#8221; image_3_rotate_sign=&#8221;+&#8221; image_3_rotate=&#8221;none&#8221; image_3_scale=&#8221;1&#8243; image_3_animation=&#8221;Fade In&#8221; image_3_padding=&#8221;auto&#8221; image_3_box_shadow=&#8221;none&#8221; image_3_max_width_desktop=&#8221;100%&#8221; image_3_max_width_mobile=&#8221;100%&#8221; image_3_image_width_mobile=&#8221;default&#8221; image_4_offset_x_sign=&#8221;+&#8221; image_4_offset_x=&#8221;0%&#8221; image_4_offset_y_sign=&#8221;+&#8221; image_4_offset_y=&#8221;0%&#8221; image_4_rotate_sign=&#8221;+&#8221; image_4_rotate=&#8221;none&#8221; image_4_scale=&#8221;1&#8243; image_4_animation=&#8221;Fade In&#8221; image_4_padding=&#8221;auto&#8221; image_4_box_shadow=&#8221;none&#8221; image_4_max_width_desktop=&#8221;100%&#8221; image_4_max_width_mobile=&#8221;100%&#8221; image_4_image_width_mobile=&#8221;default&#8221; element_sizing=&#8221;default&#8221; image_loading=&#8221;default&#8221; border_radius=&#8221;none&#8221; overflow=&#8221;visible&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2><span style=\"color: #00a2da;\"><strong>Michelle Kopriva, RN, BSN, CIC<\/strong><\/span><\/h2>\n[\/vc_column_text][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;default&#8221; line_thickness=&#8221;2&#8243; divider_color=&#8221;default&#8221; animate=&#8221;yes&#8221; custom_height=&#8221;40&#8243;][vc_column_text]\n<p style=\"text-align: justify;\">Michelle received her Associate Nursing Degree from North Idaho College in 2004 and her Bachelor of Science degree in Nursing from Lewis and Clark State College in 2009. She completed rotations at Kootenai Medical Center and Spokane Valley General Hospital during that time. Michelle is a native of Coeur d\u2019Alene, Idaho and has been with the Coeur d\u2019Alene Foot &amp; Ankle Clinic \/ Surgery Center since 2004 and serves as the Clinical &amp; Surgical Nurse Manager. She obtained her certification in infection control (CIC) in 2017 to continue to best meet the stringent requirements of managing a Medicare Certified Surgery Center.\u00a0 Michelle has also been assisting at the Academy of Ambulatory Foot &amp; Ankle Surgery Cadaver Seminars since 2006. She is board certified in infection control and epidemiology.<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;288&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;118&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;200&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-100&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;55&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243; img_link=&#8221;https:\/\/www.cdafootankle.com\/home\/services\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;56&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243; img_link=&#8221;https:\/\/www.cdafootankle.com\/home\/mis\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;58&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243; img_link=&#8221;https:\/\/www.cdafootankle.com\/home\/appointments\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;57&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;5px&#8221; box_shadow=&#8221;small_depth&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; delay=&#8221;600&#8243; img_link=&#8221;https:\/\/www.cdafootankle.com\/home\/patients-forms\/&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-100&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;119&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#284c66&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;150&#8243; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-50&#8243; bottom_margin=&#8221;50&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;medium_depth&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;700&#8243; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text]\n<h3><span style=\"color: #00a4dc;\">REQUEST AN APPOINTMENT<\/span><\/h3>\n[\/vc_column_text][vc_column_text]Please call us at (208) 666-0605 or fill out the form below<br \/>\nto submit your information[\/vc_column_text][vc_column_text]<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-35\"><form id=\"wpforms-form-35\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"35\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/home\/wp-json\/wp\/v2\/pages\/283\" data-token=\"d8ea9c72828043d4fca05f9355ff8827\" data-token-time=\"1778701071\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-35-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-35-field_1\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-35-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-35-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-35-field_2\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-35-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-35-field_9-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-35-field_9\">Phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-35-field_9\" class=\"wpforms-field-medium wpforms-field-required wpforms-masked-input\" data-inputmask=\"&#039;mask&#039;: &#039;(999) 999-9999&#039;\" data-rule-us-phone-field=\"true\" data-inputmask-inputmode=\"tel\" name=\"wpforms[fields][9]\" aria-label=\"Phone\" required><\/div><div id=\"wpforms-35-field_10-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"10\"><label class=\"wpforms-field-label\">Date \/ Time <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-date-type-datepicker\"><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-35-field_10\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][10][date]\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><label for=\"wpforms-35-field_10\" class=\"wpforms-field-sublabel after\">Date<\/label><\/div><div class=\"wpforms-field-row-block\"><input type=\"text\" id=\"wpforms-35-field_10-time\" class=\"wpforms-field-date-time-time wpforms-timepicker wpforms-field-required\" data-time-format=\"g:i A\" data-step=\"30\" data-rule-time12h=\"true\" name=\"wpforms[fields][10][time]\" required><label for=\"wpforms-35-field_10-time\" class=\"wpforms-field-sublabel after\">Time<\/label><\/div><\/div><\/div><div id=\"wpforms-35-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-35-field_7\">Nature of this appointment:<\/label><textarea id=\"wpforms-35-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"35\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages\/283\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-35\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cdafootankle.com\/home\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;fade-in&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;119&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-283","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Meet Our Team - CDA Foot and Ankle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meet Our Team - CDA Foot and Ankle\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;119&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/\" \/>\n<meta property=\"og:site_name\" content=\"CDA Foot and Ankle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cdafootandankle\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-08T14:37:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/\",\"url\":\"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/\",\"name\":\"Meet Our Team - CDA Foot and Ankle\",\"isPartOf\":{\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#website\"},\"datePublished\":\"2022-03-29T15:55:21+00:00\",\"dateModified\":\"2023-05-08T14:37:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cdafootankle.com\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meet Our Team\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#website\",\"url\":\"https:\/\/www.cdafootankle.com\/home\/\",\"name\":\"CDA Foot and Ankle\",\"description\":\"Minimally Invasive Foot Surgery\",\"publisher\":{\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#organization\"},\"alternateName\":\"Minimally Invasive Foot Surgery\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cdafootankle.com\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#organization\",\"name\":\"CDA Foot and Ankle\",\"alternateName\":\"Minimally Invasive Foot Surgery\",\"url\":\"https:\/\/www.cdafootankle.com\/home\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2023\/04\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2023\/04\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"CDA Foot and Ankle\"},\"image\":{\"@id\":\"https:\/\/www.cdafootankle.com\/home\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cdafootandankle\/\",\"https:\/\/www.instagram.com\/cdafootankle\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meet Our Team - CDA Foot and Ankle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/","og_locale":"en_US","og_type":"article","og_title":"Meet Our Team - CDA Foot and Ankle","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;119&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;waves_opacity_alt&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221;...","og_url":"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/","og_site_name":"CDA Foot and Ankle","article_publisher":"https:\/\/www.facebook.com\/cdafootandankle\/","article_modified_time":"2023-05-08T14:37:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/","url":"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/","name":"Meet Our Team - CDA Foot and Ankle","isPartOf":{"@id":"https:\/\/www.cdafootankle.com\/home\/#website"},"datePublished":"2022-03-29T15:55:21+00:00","dateModified":"2023-05-08T14:37:43+00:00","breadcrumb":{"@id":"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cdafootankle.com\/home\/meet-our-team\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cdafootankle.com\/home\/meet-our-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cdafootankle.com\/home\/"},{"@type":"ListItem","position":2,"name":"Meet Our Team"}]},{"@type":"WebSite","@id":"https:\/\/www.cdafootankle.com\/home\/#website","url":"https:\/\/www.cdafootankle.com\/home\/","name":"CDA Foot and Ankle","description":"Minimally Invasive Foot Surgery","publisher":{"@id":"https:\/\/www.cdafootankle.com\/home\/#organization"},"alternateName":"Minimally Invasive Foot Surgery","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cdafootankle.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cdafootankle.com\/home\/#organization","name":"CDA Foot and Ankle","alternateName":"Minimally Invasive Foot Surgery","url":"https:\/\/www.cdafootankle.com\/home\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cdafootankle.com\/home\/#\/schema\/logo\/image\/","url":"https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2023\/04\/cropped-favicon.png","contentUrl":"https:\/\/www.cdafootankle.com\/home\/wp-content\/uploads\/2023\/04\/cropped-favicon.png","width":512,"height":512,"caption":"CDA Foot and Ankle"},"image":{"@id":"https:\/\/www.cdafootankle.com\/home\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cdafootandankle\/","https:\/\/www.instagram.com\/cdafootankle\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages\/283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/comments?post=283"}],"version-history":[{"count":9,"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages\/283\/revisions"}],"predecessor-version":[{"id":1047,"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/pages\/283\/revisions\/1047"}],"wp:attachment":[{"href":"https:\/\/www.cdafootankle.com\/home\/wp-json\/wp\/v2\/media?parent=283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}